{"id":12068,"date":"2026-07-14T17:46:44","date_gmt":"2026-07-14T14:46:44","guid":{"rendered":"https:\/\/marocsportlive.com\/la-france-et-lespagne-organisent-la-finale-la-plus-couteuse-de-lhistoire-de-la-coupe-du-monde-299-milliards-de-dollars-investis-dans-le-stade\/"},"modified":"2026-07-14T17:47:16","modified_gmt":"2026-07-14T14:47:16","slug":"la-france-et-lespagne-organisent-la-finale-la-plus-couteuse-de-lhistoire-de-la-coupe-du-monde-299-milliards-de-dollars-investis-dans-le-stade","status":"publish","type":"post","link":"https:\/\/marocsportlive.com\/fr\/la-france-et-lespagne-organisent-la-finale-la-plus-couteuse-de-lhistoire-de-la-coupe-du-monde-299-milliards-de-dollars-investis-dans-le-stade\/","title":{"rendered":"La France et l&rsquo;Espagne organisent la finale la plus co\u00fbteuse de l&rsquo;histoire de la Coupe du monde\u2026 2,99 milliards de dollars investis dans le stade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La rencontre entre la France et l&rsquo;Espagne en demi-finale de la Coupe du monde 2026 ne rev\u00eat pas seulement une importance footballistique, en tant qu&rsquo;\u00e9tape d\u00e9cisive vers la finale, mais elle entre \u00e9galement dans l&rsquo;histoire comme le match le plus \u00ab cher \u00bb de l&rsquo;histoire des phases finales de la Coupe du monde en termes de valeur marchande des joueurs.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce mardi soir, tous les regards des amateurs de football se tournent vers le stade \u00ab AT&#038;T \u00bb, qui accueille le choc tr\u00e8s attendu entre les deux \u00e9quipes, dans un match que beaucoup qualifient de \u00ab finale avant l&rsquo;heure \u00bb, compte tenu de la puissance des deux \u00e9quipes et du nombre de stars pr\u00e9sentes dans leurs effectifs respectifs.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux \u00e9quipes se sont qualifi\u00e9es pour les demi-finales apr\u00e8s un parcours remarquable dans ce tournoi organis\u00e9 aux \u00c9tats-Unis, au Canada et au Mexique. La France s\u2019est qualifi\u00e9e apr\u00e8s avoir battu le Maroc 2-0, gr\u00e2ce \u00e0 des buts de Kylian Mbapp\u00e9 et Ousmane Demb\u00e9l\u00e9, tandis que l\u2019Espagne a d\u00e9croch\u00e9 son billet pour les demi-finales \u00e0 l\u2019issue d\u2019une victoire difficile contre le Portugal, gr\u00e2ce \u00e0 un but inscrit en fin de match par le rempla\u00e7ant Mikel Merino.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce match arrive en t\u00eate de toutes les rencontres de la Coupe du monde 2026 en termes de valeur marchande, la valeur totale des joueurs des deux \u00e9quipes s&rsquo;\u00e9levant \u00e0 environ 2,99 milliards de dollars, selon les donn\u00e9es du site \u00ab Transfermarkt \u00bb, ce qui en fait la rencontre la plus ch\u00e8re de l&rsquo;histoire de la Coupe du monde.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La valeur marchande de l&rsquo;\u00e9quipe de France s&rsquo;\u00e9l\u00e8ve \u00e0 1,66 milliard de dollars, contre 1,33 milliard de dollars pour l&rsquo;\u00e9quipe d&rsquo;Espagne, soit un \u00e9cart d&rsquo;environ 327 millions de dollars en faveur des \u00ab Bleus \u00bb.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce match oppose quatre des cinq joueurs les plus chers du championnat, avec en t\u00eate l&rsquo;Espagnol Lamine Yamal, dont la valeur de march\u00e9 s&rsquo;\u00e9l\u00e8ve \u00e0 218 millions de dollars, soit le m\u00eame montant que celui du Norv\u00e9gien Erling Haaland.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est suivi par le Fran\u00e7ais Kylian Mbapp\u00e9, avec une valeur de 196,2 millions de dollars, puis par le Fran\u00e7ais Michael Olis et l&rsquo;Espagnol Pedri Gonz\u00e1lez, dont la valeur s&rsquo;\u00e9l\u00e8ve \u00e0 163,5 millions de dollars chacun.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et l&rsquo;impressionnant bilan chiffr\u00e9 ne se limite pas aux grands noms : ce match verra en effet s&rsquo;affronter sept joueurs dont la valeur de march\u00e9 d\u00e9passe chacun les 109 millions de dollars. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce classement comprend \u00e9galement 22 joueurs dont la valeur d\u00e9passe chacun 54,5 millions de dollars, dont 15 \u00e9voluent au sein de l&rsquo;\u00e9quipe de France, contre sept au sein de l&rsquo;\u00e9quipe d&rsquo;Espagne.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au niveau des postes, l&rsquo;\u00e9quipe d&rsquo;Espagne devance la France en termes de valeur des gardiens de but, la valeur totale de ses trois gardiens s&rsquo;\u00e9levant \u00e0 105,7 millions de dollars, contre 62,1 millions de dollars pour ceux de l&rsquo;\u00e9quipe de France.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En revanche, l&rsquo;\u00e9quipe de France dispose d&rsquo;un net avantage en d\u00e9fense, avec une valeur de march\u00e9 s&rsquo;\u00e9levant \u00e0 440,4 millions de dollars, contre 313,9 millions de dollars pour l&rsquo;\u00e9quipe d&rsquo;Espagne.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au milieu de terrain, l&rsquo;Espagne affiche une valeur totale de 457,8 millions de dollars, contre 340,1 millions de dollars pour le milieu de terrain de l&rsquo;\u00e9quipe de France, ce qui refl\u00e8te la puissance de \u00ab La Roja \u00bb dans la zone de contr\u00f4le et la construction du jeu.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais c&rsquo;est en attaque que la France affiche sa plus grande sup\u00e9riorit\u00e9 : la valeur marchande de l&rsquo;attaque des \u00ab Bleus \u00bb s&rsquo;\u00e9l\u00e8ve \u00e0 817,5 millions de dollars, ce qui repr\u00e9sente un \u00e9cart consid\u00e9rable par rapport \u00e0 celle de l&rsquo;Espagne, bien que la s\u00e9lection espagnole compte dans ses rangs le joueur le plus cher de la rencontre, Lamine Yamal.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre les paris sportifs et les chiffres financiers colossaux, le choc entre la France et l\u2019Espagne s\u2019annonce comme l\u2019un des matchs les plus attendus de la Coupe du monde 2026, non seulement parce qu\u2019il rapprochera le vainqueur du titre, mais aussi parce qu\u2019il r\u00e9unira sur un m\u00eame terrain l\u2019\u00e9lite des stars les plus ch\u00e8res du football mondial.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rencontre entre la France et l&rsquo;Espagne en demi-finale de la Coupe du monde 2026 ne rev\u00eat pas seulement une importance footballistique, en tant qu&rsquo;\u00e9tape d\u00e9cisive vers la finale, mais&hellip;<\/p>\n","protected":false},"author":2,"featured_media":12057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[58],"tags":[],"class_list":["post-12068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football-mondial"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"_links":{"self":[{"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/posts\/12068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/comments?post=12068"}],"version-history":[{"count":0,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/posts\/12068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/media\/12057"}],"wp:attachment":[{"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/media?parent=12068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/categories?post=12068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marocsportlive.com\/fr\/wp-json\/wp\/v2\/tags?post=12068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}